{"id":9274,"date":"2015-11-02T14:36:27","date_gmt":"2015-11-02T13:36:27","guid":{"rendered":"http:\/\/www.campamentum.com\/blog\/?p=9274"},"modified":"2020-06-22T16:01:44","modified_gmt":"2020-06-22T14:01:44","slug":"campamento-urbano-o-naturaleza","status":"publish","type":"post","link":"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/","title":{"rendered":"Campamento urbano o en la naturaleza \u00bfCu\u00e1l elegir?"},"content":{"rendered":"<div class=\"d7674e24c07d6f3f3f96bf009318d221\" data-index=\"1\" style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- blog-300x250 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:300px;height:250px\"\r\n     data-ad-client=\"ca-pub-5066720444154486\"\r\n     data-ad-slot=\"7632222965\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>La eterna duda cuando decidimos hacer uno de estos campamentos. \u00bfEs mejor un\u00a0<strong>campamento en la naturaleza<\/strong>? \u00bfUn\u00a0<strong>campamento urbano<\/strong>\u00a0es m\u00e1s barato? Es normal que nos hagamos este tipo de preguntas. Al fin y al cabo, no se trata de una decisi\u00f3n f\u00e1cil. Pero es importante que partamos de la idea que <strong>t<\/strong>anto los cursos de verano que se realizan en el campo como los que se llevan a cabo en la ciudad tienen tanto ventajas como desventajas.<\/p>\n<h2>Caracter\u00edsticas de los campamentos en la naturaleza<\/h2>\n<p>Un campamento\u00a0de verano en el campo o en la monta\u00f1a debe tener un buen programa de deportes y actividades: <strong>pirag\u00fcismo, senderismo, talleres de artesan\u00eda<\/strong>\u2026 Las inmersiones en ambientes naturales se prestan a este tipo de iniciativas. Por supuesto, tambi\u00e9n es esencial que el centro ofrezca un buen programa de idiomas, pero sobre todo, que te permita disfrutar durante unas semanas de un entorno natural incomparable.<\/p>\n<p><a class=\"btn btn-verde btnPortada\" href=\"\/\">Los mejores campamentos de verano<\/a><\/p>\n<p>Debes recordar que un campamento en la naturaleza no s\u00f3lo sirve para practicar un idioma. Aprender a respetar y disfrutar de la naturaleza es igual o incluso m\u00e1s importante que el ingl\u00e9s o el franc\u00e9s; y las experiencias que puedes vivir durante los meses de vacaciones junto a los compa\u00f1eros, seguro ser\u00e1n inolvidables.<\/p>\n<h2>Lugares<\/h2>\n<p>Una de las decisiones m\u00e1s importantes a la hora de realizar un campamento de verano en la naturaleza es elegir d\u00f3nde hacerlo. Uno de los mejores sitios son <a href=\"https:\/\/es.wikipedia.org\/wiki\/Pirineos\" target=\"_blank\" rel=\"noopener noreferrer\">Los Pirineos<\/a>, donde podemos encontrar diversas posibilidades de alojamiento como las residencias en la zona de Jaca, \u00a0\u00a1d\u00f3nde incluso puedes practicar patinaje sobre hielo en verano!<\/p>\n<p>Las sierras de Gredos y de Guadarrama son otra gran opci\u00f3n si vives en el centro de la pen\u00ednsula. Su cercan\u00eda a Madrid ayuda a que se organicen excursiones a parques de atracciones, sin olvidar actividades m\u00e1s t\u00edpicas de monta\u00f1a (tirolina, canoa, tiro con arco\u2026) o relacionadas con los deportes de equipo (futbol, baloncesto\u2026), siendo <strong>&gt;Hyland<\/strong> o <strong>CIDI<\/strong> excelentes elecciones si optas por la sierra madrile\u00f1a.<\/p>\n<h2>Actividades<\/h2>\n<p>Aparte de las t\u00edpicas excursiones y juegos deportivos, los campamentos de verano en la naturaleza suelen incluir otro tipo de actividades \u201cespeciales\u201d: piscina, tiro con arco, bicicleta, roc\u00f3dromo, tirolina, rapel\u2026. Por lo tanto, no s\u00f3lo estamos hablando de clases en ingl\u00e9s o franc\u00e9s, sino tambi\u00e9n de cursos intensivos de deporte y conocimiento de la naturaleza. Incluso en muchos de estos centros puedes encontrar actividades m\u00e1s extraordinarias, como las clases de h\u00edpica, rastreo o artesan\u00eda que ofrece <strong>Barling School<\/strong>.<\/p><div class=\"d7674e24c07d6f3f3f96bf009318d221\" data-index=\"1\" style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- blog-300x250 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:300px;height:250px\"\r\n     data-ad-client=\"ca-pub-5066720444154486\"\r\n     data-ad-slot=\"7632222965\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n\n<h2>Caracter\u00edsticas de un\u00a0campamento urbano<\/h2>\n<p>Muy a menudo se suele pensar que los campamentos de verano\u00a0en el campo o la monta\u00f1a son mucho mejores que un campamento urbano. Nada m\u00e1s lejos de la realidad. Un\u00a0campamento urbano dispone de una gran oferta de <strong>actividades deportivas, culturales y tur\u00edsticas<\/strong> (museos, monumentos, parques de atracciones, excursiones\u2026). Adem\u00e1s, es\u00a0una excelente opci\u00f3n sino quieres realizar grandes desplazamientos, y es\u00a0m\u00e1s barato que las colonias\u00a0de verano en la naturaleza.<\/p>\n<p><a class=\"btn btn-verde btnPortada\" href=\"\/campamentos\/modalidad-urbanos\/\">Los mejores campamentos urbanos<\/a><\/p>\n<h2>Ciudades<\/h2>\n<p>Las dos ciudades con una mayor oferta para realizar un campamento urbano son\u00a0<strong>Madrid y Salamanca<\/strong>, la ciudad de los estudiantes por excelencia. En ambas puedes encontrar diversos programas en los que las actividades culturales y deportivas se integren a la perfecci\u00f3n con el aprendizaje de idiomas. Adem\u00e1s, resulta mucho m\u00e1s sencillo encontrar en un\u00a0campamento urbano programas de inmersi\u00f3n en los que poder aprender otros idiomas aparte del ingl\u00e9s. <strong>Eduma<\/strong> o <strong>Alliance Fran\u00e7aise<\/strong> de Madrid son dos claros ejemplos de ello, pues tambi\u00e9n ofrecen franc\u00e9s en sus campamentos urbanos, l\u00fadicos, deportivos y culturales que desarrollan en Salamanca, Toledo o Madrid.<\/p>\n<p>Tambi\u00e9n en Madrid, otros centros ofrecen programas para mayores de edad\u00a0o tem\u00e1ticos, como los campamentos del <strong>Instituto Internacional<\/strong>, una de las mejores opciones si quieres disfrutar de un amplio repertorio de actividades culturales: arte, teatro, m\u00fasica, turismo, etc.<\/p>\n<h2>Actividades<\/h2>\n<p>Deportivas, culturales, tur\u00edsticas\u2026 Si pensabas un\u00a0campamento urbano ofrece\u00a0programas m\u00e1s austeros que los realizados en entornos naturales estabas muy equivocado. Este tipo de centros suelen combinar diversas actividades deportivas en equipo (f\u00fatbol, baloncesto, piscina, etc.) con visitas a museos, teatros, cines, parques de atracciones, monumentos\u2026<\/p>\n<p>En definitiva, realizar un campamentos de verano en la naturaleza o por el contrario asistir a un\u00a0campamento urbano\u00a0tienen tanto sus ventajas como sus desventajas. No pienses que unos son mejores que otros. Todo depender\u00e1 de tus gustos y experiencias. As\u00ed que tras \u00e9stas l\u00edneas s\u00f3lo queda plantearte una pregunta:<\/p>\n<p>\u00bfEres de campo o de ciudad?<\/p>\n<!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A veces nos cuesta decidirnos sobre qu\u00e9 tipo de campamento elegir: campamento urbano o campamento de naturaleza. Hoy arrojamos un poco de luz sobre este tipo de colonias de verano.<\/p>\n","protected":false},"author":1,"featured_media":9275,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[13],"tags":[],"class_list":["post-9274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consejos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Urbanos o en la Naturaleza \u00bfQu\u00e9 Campamento Elegir?<\/title>\n<meta name=\"description\" content=\"Descubre los pros y contras de cada uno, y as\u00ed poderte decantar entre un campamento urbano o una colonia de verano en la naturaleza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Urbanos o en la Naturaleza \u00bfQu\u00e9 Campamento Elegir?\" \/>\n<meta property=\"og:description\" content=\"Descubre los pros y contras de cada uno, y as\u00ed poderte decantar entre un campamento urbano o una colonia de verano en la naturaleza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de los campamentos de verano - Campamentum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/campamentum\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-02T13:36:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-22T14:01:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campamentum.com\/blog\/wp-content\/uploads\/2015\/11\/campamento-urbano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campamentum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Campamentum\" \/>\n<meta name=\"twitter:site\" content=\"@Campamentum\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campamentum\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/\"},\"author\":{\"name\":\"Campamentum\",\"@id\":\"https:\/\/www.campamentum.com\/blog\/#\/schema\/person\/3a6a118d1c47fc58ebf0b288e015f948\"},\"headline\":\"Campamento urbano o en la naturaleza \u00bfCu\u00e1l elegir?\",\"datePublished\":\"2015-11-02T13:36:27+00:00\",\"dateModified\":\"2020-06-22T14:01:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/\"},\"wordCount\":803,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.campamentum.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.campamentum.com\/blog\/wp-content\/uploads\/2015\/11\/campamento-urbano.jpg\",\"articleSection\":[\"Consejos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/\",\"url\":\"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/\",\"name\":\"Urbanos o en la Naturaleza \u00bfQu\u00e9 Campamento Elegir?\",\"isPartOf\":{\"@id\":\"https:\/\/www.campamentum.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.campamentum.com\/blog\/wp-content\/uploads\/2015\/11\/campamento-urbano.jpg\",\"datePublished\":\"2015-11-02T13:36:27+00:00\",\"dateModified\":\"2020-06-22T14:01:44+00:00\",\"description\":\"Descubre los pros y contras de cada uno, y as\u00ed poderte decantar entre un campamento urbano o una colonia de verano en la naturaleza\",\"breadcrumb\":{\"@id\":\"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/#primaryimage\",\"url\":\"https:\/\/www.campamentum.com\/blog\/wp-content\/uploads\/2015\/11\/campamento-urbano.jpg\",\"contentUrl\":\"https:\/\/www.campamentum.com\/blog\/wp-content\/uploads\/2015\/11\/campamento-urbano.jpg\",\"width\":750,\"height\":350,\"caption\":\"campamento urbano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"blog\",\"item\":\"https:\/\/www.campamentum.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consejos\",\"item\":\"https:\/\/www.campamentum.com\/blog\/consejos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Campamento urbano o en la naturaleza \u00bfCu\u00e1l elegir?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.campamentum.com\/blog\/#website\",\"url\":\"https:\/\/www.campamentum.com\/blog\/\",\"name\":\"El Blog de los campamentos de verano - Campamentum\",\"description\":\"Noticias, Curiosidades, consejos y mucho m\u00e1s en el blog de los campamentos de verano de Campamentum\",\"publisher\":{\"@id\":\"https:\/\/www.campamentum.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.campamentum.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.campamentum.com\/blog\/#organization\",\"name\":\"Campamentum\",\"url\":\"https:\/\/www.campamentum.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.campamentum.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.campamentum.com\/blog\/wp-content\/uploads\/2015\/10\/campamentum-blog-logo.png\",\"contentUrl\":\"https:\/\/www.campamentum.com\/blog\/wp-content\/uploads\/2015\/10\/campamentum-blog-logo.png\",\"width\":252,\"height\":48,\"caption\":\"Campamentum\"},\"image\":{\"@id\":\"https:\/\/www.campamentum.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/campamentum\",\"https:\/\/x.com\/Campamentum\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.campamentum.com\/blog\/#\/schema\/person\/3a6a118d1c47fc58ebf0b288e015f948\",\"name\":\"Campamentum\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.campamentum.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e5c84880edb6f273c30d62357d2f744f2323f363a4be3f016c1f6785f2a5edbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e5c84880edb6f273c30d62357d2f744f2323f363a4be3f016c1f6785f2a5edbe?s=96&d=mm&r=g\",\"caption\":\"Campamentum\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Urbanos o en la Naturaleza \u00bfQu\u00e9 Campamento Elegir?","description":"Descubre los pros y contras de cada uno, y as\u00ed poderte decantar entre un campamento urbano o una colonia de verano en la naturaleza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/","og_locale":"es_ES","og_type":"article","og_title":"Urbanos o en la Naturaleza \u00bfQu\u00e9 Campamento Elegir?","og_description":"Descubre los pros y contras de cada uno, y as\u00ed poderte decantar entre un campamento urbano o una colonia de verano en la naturaleza","og_url":"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/","og_site_name":"El Blog de los campamentos de verano - Campamentum","article_publisher":"https:\/\/www.facebook.com\/campamentum","article_published_time":"2015-11-02T13:36:27+00:00","article_modified_time":"2020-06-22T14:01:44+00:00","og_image":[{"width":750,"height":350,"url":"https:\/\/www.campamentum.com\/blog\/wp-content\/uploads\/2015\/11\/campamento-urbano.jpg","type":"image\/jpeg"}],"author":"Campamentum","twitter_card":"summary_large_image","twitter_creator":"@Campamentum","twitter_site":"@Campamentum","twitter_misc":{"Escrito por":"Campamentum","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/#article","isPartOf":{"@id":"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/"},"author":{"name":"Campamentum","@id":"https:\/\/www.campamentum.com\/blog\/#\/schema\/person\/3a6a118d1c47fc58ebf0b288e015f948"},"headline":"Campamento urbano o en la naturaleza \u00bfCu\u00e1l elegir?","datePublished":"2015-11-02T13:36:27+00:00","dateModified":"2020-06-22T14:01:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/"},"wordCount":803,"commentCount":0,"publisher":{"@id":"https:\/\/www.campamentum.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campamentum.com\/blog\/wp-content\/uploads\/2015\/11\/campamento-urbano.jpg","articleSection":["Consejos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/","url":"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/","name":"Urbanos o en la Naturaleza \u00bfQu\u00e9 Campamento Elegir?","isPartOf":{"@id":"https:\/\/www.campamentum.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/#primaryimage"},"image":{"@id":"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campamentum.com\/blog\/wp-content\/uploads\/2015\/11\/campamento-urbano.jpg","datePublished":"2015-11-02T13:36:27+00:00","dateModified":"2020-06-22T14:01:44+00:00","description":"Descubre los pros y contras de cada uno, y as\u00ed poderte decantar entre un campamento urbano o una colonia de verano en la naturaleza","breadcrumb":{"@id":"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/#primaryimage","url":"https:\/\/www.campamentum.com\/blog\/wp-content\/uploads\/2015\/11\/campamento-urbano.jpg","contentUrl":"https:\/\/www.campamentum.com\/blog\/wp-content\/uploads\/2015\/11\/campamento-urbano.jpg","width":750,"height":350,"caption":"campamento urbano"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campamentum.com\/blog\/campamento-urbano-o-naturaleza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"blog","item":"https:\/\/www.campamentum.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Consejos","item":"https:\/\/www.campamentum.com\/blog\/consejos\/"},{"@type":"ListItem","position":3,"name":"Campamento urbano o en la naturaleza \u00bfCu\u00e1l elegir?"}]},{"@type":"WebSite","@id":"https:\/\/www.campamentum.com\/blog\/#website","url":"https:\/\/www.campamentum.com\/blog\/","name":"El Blog de los campamentos de verano - Campamentum","description":"Noticias, Curiosidades, consejos y mucho m\u00e1s en el blog de los campamentos de verano de Campamentum","publisher":{"@id":"https:\/\/www.campamentum.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campamentum.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.campamentum.com\/blog\/#organization","name":"Campamentum","url":"https:\/\/www.campamentum.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campamentum.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.campamentum.com\/blog\/wp-content\/uploads\/2015\/10\/campamentum-blog-logo.png","contentUrl":"https:\/\/www.campamentum.com\/blog\/wp-content\/uploads\/2015\/10\/campamentum-blog-logo.png","width":252,"height":48,"caption":"Campamentum"},"image":{"@id":"https:\/\/www.campamentum.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/campamentum","https:\/\/x.com\/Campamentum"]},{"@type":"Person","@id":"https:\/\/www.campamentum.com\/blog\/#\/schema\/person\/3a6a118d1c47fc58ebf0b288e015f948","name":"Campamentum","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campamentum.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e5c84880edb6f273c30d62357d2f744f2323f363a4be3f016c1f6785f2a5edbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5c84880edb6f273c30d62357d2f744f2323f363a4be3f016c1f6785f2a5edbe?s=96&d=mm&r=g","caption":"Campamentum"}}]}},"_links":{"self":[{"href":"https:\/\/www.campamentum.com\/blog\/wp-json\/wp\/v2\/posts\/9274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campamentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campamentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campamentum.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campamentum.com\/blog\/wp-json\/wp\/v2\/comments?post=9274"}],"version-history":[{"count":13,"href":"https:\/\/www.campamentum.com\/blog\/wp-json\/wp\/v2\/posts\/9274\/revisions"}],"predecessor-version":[{"id":9919,"href":"https:\/\/www.campamentum.com\/blog\/wp-json\/wp\/v2\/posts\/9274\/revisions\/9919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campamentum.com\/blog\/wp-json\/wp\/v2\/media\/9275"}],"wp:attachment":[{"href":"https:\/\/www.campamentum.com\/blog\/wp-json\/wp\/v2\/media?parent=9274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campamentum.com\/blog\/wp-json\/wp\/v2\/categories?post=9274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campamentum.com\/blog\/wp-json\/wp\/v2\/tags?post=9274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}